
{"id":11449,"date":"2023-11-23T07:40:25","date_gmt":"2023-11-23T07:40:25","guid":{"rendered":"https:\/\/sandsiv.com\/?p=11449"},"modified":"2023-11-23T07:40:02","modified_gmt":"2023-11-23T07:40:02","slug":"sandsiv-e-applied-consulting","status":"publish","type":"post","link":"https:\/\/sandsiv.com\/it\/sandsiv-e-applied-consulting\/","title":{"rendered":"SANDSIV e Applied Consulting"},"content":{"rendered":"<div id=\"banner-block_1d63c4b5b69a665f8852210e6ae2e344\"\r\n    class=\"banner scroll-fade\">\r\n    <div\r\n        class=\"module mt_0 \">\r\n        <div class=\"container\">\r\n            <div class=\"banner__inner\">\r\n                <div class=\"banner__data\">\r\n                                        <h1 class=\"heading\">Breaking News <strong\r\n                            class=\"heading_red\">SANDSIV e Applied Consulting<\/strong>                    <\/h1>\r\n                                                            <div class=\"description\">SANDSIV e Applied Consulting Rivoluzionano l&#8217;Esperienza del Cliente in Italia                    <\/div>                                                            <div class=\"banner__button\">\r\n                        <a href=\"https:\/\/sandsiv.com\/it\/contattaci\/\"\r\n                            class=\"btn\" _self                            >Contattaci<\/a>\r\n                    <\/div>\r\n                                                                            <\/div>\r\n                <div class=\"banner__media\">\r\n                                        <div class=\"banner__image\">\r\n                        <picture class=\"image\">\r\n                            <source srcset=\"https:\/\/sandsiv.com\/wp-content\/uploads\/2023\/11\/webpage-applied-consulting.png\">\r\n                            <img decoding=\"async\" src=\"https:\/\/sandsiv.com\/wp-content\/uploads\/2023\/11\/webpage-applied-consulting.png\"\r\n                                alt=\"\" \/>\r\n                        <\/picture>\r\n                    <\/div>\r\n                                                                            <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\n\n\r\n<div id=\"post_content_with_video-block_97dfa1ad75635dac237866d00b421c27\" class=\"post_content_with_video scroll-fade\">\r\n    <div class=\"module \">                \r\n\r\n                    <div class=\"container\">\r\n                                                                                    <div class=\"post_content_with_video_inner\"> \r\n                                                                                                <div class=\"heading_section\">\r\n                                        <div class=\"heading_text h2\">\r\n                                            Una Partnership Dinamica per Promuovere la Centralit\u00e0 del Cliente e l&#8217;Innovazione Aziendale                                        <\/div>\r\n                                    <\/div>\r\n                                                                                                                    \r\n                                                                                                <div class=\"content_section\">\r\n                                        <p><b>Zurich, Switzerland \u2013 <\/b><b>23 novembre<\/b><b>, 2023\u00a0 \u2014 <\/b><span style=\"color: #bf2025;\"><a style=\"color: #bf2025;\" href=\"https:\/\/sandsiv.com\/\"><span style=\"font-weight: 400;\">SANDSIV<\/span><\/a><\/span><span style=\"font-weight: 400;\">, leader nella fornitura di tecnologie per la Customer Experience (CX) e la Voice of Customer attraverso la sua innovativa piattaforma aziendale sandsiv+, \u00e8 entusiasta di annunciare una collaborazione strategica con <\/span><a href=\"https:\/\/www.appliedconsulting.it\/\"><span style=\"font-weight: 400;\"><span style=\"color: #bf2025;\">Applied Consulting<\/span><\/span><\/a><span style=\"font-weight: 400;\"><span style=\"color: #bf2025;\">,<\/span> boutique di consulenza direzionale specializzata nella semplificazione dei processi aziendali e nella crescita sostenibile attraverso un approccio centrato sul cliente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Questa partnership combina le competenze distintive di Applied Consulting e SANDSIV, entrambe impegnate nella stessa missione: supportare le aziende nel raggiungere la <\/span><i><span style=\"font-weight: 400;\">Customer Centricity, il People Engagement<\/span><\/i><span style=\"font-weight: 400;\"> e l&#8217;<\/span><i><span style=\"font-weight: 400;\">Operational Excellence<\/span><\/i><span style=\"font-weight: 400;\">. Unendo la piattaforma sandsiv+ per la Voice of the Customer con servizi di consulenza strategica, lavorano insieme per guidare le aziende attraverso fasi di trasformazione, facilitando l&#8217;innovazione attraverso metodologie consolidate.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L&#8217;obiettivo di questa collaborazione \u00e8 ridefinire il panorama dell&#8217;esperienza del cliente, sfruttando la soluzione sandsiv+ CX all&#8217;avanguardia di SANDSIV. Ci\u00f2 consente alle aziende non solo di catturare, ma anche di analizzare efficacemente i feedback dei clienti, permettendo loro di adottare misure proattive basate su preziose intuizioni.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Scoprite l&#8217;innovazione di SANDSIV attraverso la sua piattaforma sandsiv+, in collaborazione con Applied Consulting, per una rivoluzione globale nell&#8217;esperienza del cliente su <\/span><span style=\"color: #bf2025;\"><a style=\"color: #bf2025;\" href=\"https:\/\/sandsiv.com\/it\/programma-partners\"><span style=\"font-weight: 400;\">https:\/\/sandsiv.com\/it\/programma-partners\/<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/span><\/p>\n<h4><span style=\"color: #bf2025;\"><b>Flash quotes:<\/b><\/span><\/h4>\n<p><span style=\"font-weight: 400;\">Mirko Buonerba, Global Partnership Manager di SANDSIV, ha dichiarato: <em>&#8220;Numerose aziende in Italia hanno compreso l&#8217;importanza di adottare un approccio Customer-Focused, allineando persone, processi e sistemi per generare valore in base alle esigenze del cliente. La definizione, gestione e implementazione di tali iniziative richiedono il giusto supporto e la giusta tecnologia. Ecco il valore che Applied Consulting e SANDSIV apportano&#8221;.<\/em><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cristiana Luzi, Partner di Applied Consulting, ha commentato: <em>&#8220;Assistendo alla crescita del mercato e osservando nuovi settori abbracciare la tendenza della CX, siamo entusiasti di presentare una soluzione innovativa come sandsiv+. La nostra collaborazione con SANDSIV \u00e8 destinata a lasciare un&#8217;impronta duratura nell&#8217;evoluzione della Customer Experience in Italia&#8221;.<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">###<\/span><\/p>\n<h4><span style=\"color: #bf2025;\"><b>Profili delle aziende:\u00a0<\/b><\/span><\/h4>\n<p><span style=\"font-weight: 400;\">SANDSIV \u00e8 leader nell&#8217;innovazione delle soluzioni di Customer Experience Management (CXM). Con la sua avanzata soluzione software CXM end-to-end, SANDSIV abilita le aziende in tutto il mondo a offrire esperienze differenziate ai clienti e a promuovere una fedelt\u00e0 duratura. L&#8217;impegno per l&#8217;eccellenza e l&#8217;innovazione ha consentito l&#8217;espansione del programma di partner e l&#8217;instaurazione di una presenza globale in continua crescita. |<\/span><span style=\"color: #bf2025;\"><a style=\"color: #bf2025;\" href=\"https:\/\/sandsiv.com\/\"><span style=\"font-weight: 400;\"> www.sandsiv.com<\/span><\/a><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Applied Consulting &#8211; boutique di consulenza direzionale &#8211; da 15 anni supporta le aziende nella definizione e realizzazione di programmi di Customer Centricity, Operational Excellence e People Engagement.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">E\u2019 formata da professionisti con percorsi di carriera in primarie societ\u00e0 di consulenza ed in ruoli dirigenziali di aziende internazionali. L&#8217;esperienza multidisciplinare e la cultura di inclusione e team-work permettono di collaborare efficacemente con tutti i livelli aziendali, per una consulenza &#8220;Applicata agli Obiettivi del Cliente&#8221; | <\/span><span style=\"color: #bf2025;\"><a style=\"color: #bf2025;\" href=\"http:\/\/www.appliedconsulting.it\"><span style=\"font-weight: 400;\">www.appliedconsulting.it<\/span><\/a><\/span><\/p>\n<h4><span style=\"color: #bf2025;\"><b>Risorse correlate:<\/b><\/span><\/h4>\n<p><span style=\"color: #bf2025;\"><a style=\"color: #bf2025;\" href=\"https:\/\/sandsiv.com\/it\/sandsiv-e-strategic-management\/\"><span style=\"font-weight: 400;\">https:\/\/sandsiv.com\/it\/sandsiv-e-strategic-management\/<\/span><\/a><\/span><\/p>\n<p><a href=\"https:\/\/sandsiv.com\/it\/sandsiv-nominata-leader-spark-matrix-2023\/\"><span style=\"color: #bf2025;\"><span style=\"font-weight: 400;\">https:\/\/sandsiv.com\/it\/sandsiv-nominata-leader-spark-matrix-2023\/<\/span><\/span><\/a><\/p>\n<h4><span style=\"color: #bf2025;\"><b>Contatto con i media:<\/b><\/span><\/h4>\n<p><span style=\"font-weight: 400;\">Silvia Bell\u00f2<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Digital Marketing Manager<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">silvia.bello@sandsiv.com<\/span><\/p>\n                                    <\/div>\r\n                                                                                                                \r\n                        <\/div>\r\n                                                <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":11458,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[116],"tags":[233,177,200,201,181,182],"class_list":["post-11449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato","tag-breaking-news-it","tag-cxm-it","tag-partner-it","tag-partner-program-it","tag-sandsiv-it","tag-voc-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>SANDSIV e Applied Consulting - sandsiv+<\/title>\n<meta name=\"description\" content=\"SANDSIV e Applied Consulting firmano una partnership per promuovere la Centralit\u00e0 del Cliente e l&#039;Innovazione Aziendale in Italia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sandsiv.com\/it\/sandsiv-e-applied-consulting\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SANDSIV e Applied Consulting\" \/>\n<meta property=\"og:description\" content=\"SANDSIV e Applied Consulting firmano una partnership per promuovere la Centralit\u00e0 del Cliente e l&#039;Innovazione Aziendale in Italia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sandsiv.com\/it\/sandsiv-e-applied-consulting\/\" \/>\n<meta property=\"og:site_name\" content=\"sandsiv+\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-23T07:40:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sandsiv.com\/wp-content\/uploads\/2023\/11\/Sandsiv-social-IG-2023-11-21T162033.904.png\" \/>\n\t<meta property=\"og:image:width\" content=\"3375\" \/>\n\t<meta property=\"og:image:height\" content=\"3375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Giada Longo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giada Longo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sandsiv.com\\\/it\\\/sandsiv-e-applied-consulting\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sandsiv.com\\\/it\\\/sandsiv-e-applied-consulting\\\/\"},\"author\":{\"name\":\"Giada Longo\",\"@id\":\"https:\\\/\\\/sandsiv.com\\\/#\\\/schema\\\/person\\\/a5540ae6ab27ce7f4459b6192a72b8da\"},\"headline\":\"SANDSIV e Applied Consulting\",\"datePublished\":\"2023-11-23T07:40:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sandsiv.com\\\/it\\\/sandsiv-e-applied-consulting\\\/\"},\"wordCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/sandsiv.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sandsiv.com\\\/it\\\/sandsiv-e-applied-consulting\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sandsiv.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Sandsiv-social-IG-2023-11-21T162033.904.png\",\"keywords\":[\"breaking news\",\"cxm\",\"partner\",\"partner program\",\"sandsiv\",\"voc\"],\"articleSection\":[\"Non categorizzato\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sandsiv.com\\\/it\\\/sandsiv-e-applied-consulting\\\/\",\"url\":\"https:\\\/\\\/sandsiv.com\\\/it\\\/sandsiv-e-applied-consulting\\\/\",\"name\":\"SANDSIV e Applied Consulting - sandsiv+\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sandsiv.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sandsiv.com\\\/it\\\/sandsiv-e-applied-consulting\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sandsiv.com\\\/it\\\/sandsiv-e-applied-consulting\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sandsiv.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Sandsiv-social-IG-2023-11-21T162033.904.png\",\"datePublished\":\"2023-11-23T07:40:25+00:00\",\"description\":\"SANDSIV e Applied Consulting firmano una partnership per promuovere la Centralit\u00e0 del Cliente e l'Innovazione Aziendale in Italia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sandsiv.com\\\/it\\\/sandsiv-e-applied-consulting\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sandsiv.com\\\/it\\\/sandsiv-e-applied-consulting\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sandsiv.com\\\/it\\\/sandsiv-e-applied-consulting\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sandsiv.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Sandsiv-social-IG-2023-11-21T162033.904.png\",\"contentUrl\":\"https:\\\/\\\/sandsiv.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Sandsiv-social-IG-2023-11-21T162033.904.png\",\"width\":3375,\"height\":3375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sandsiv.com\\\/it\\\/sandsiv-e-applied-consulting\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sandsiv.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SANDSIV e Applied Consulting\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sandsiv.com\\\/#website\",\"url\":\"https:\\\/\\\/sandsiv.com\\\/\",\"name\":\"sandsiv+\",\"description\":\"Customer Intelligence Made In Switzerland\",\"publisher\":{\"@id\":\"https:\\\/\\\/sandsiv.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sandsiv.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sandsiv.com\\\/#organization\",\"name\":\"sandsiv+\",\"url\":\"https:\\\/\\\/sandsiv.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/sandsiv.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sandsiv.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logo-light-normal.svg\",\"contentUrl\":\"https:\\\/\\\/sandsiv.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logo-light-normal.svg\",\"width\":376,\"height\":67,\"caption\":\"sandsiv+\"},\"image\":{\"@id\":\"https:\\\/\\\/sandsiv.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sandsiv.com\\\/#\\\/schema\\\/person\\\/a5540ae6ab27ce7f4459b6192a72b8da\",\"name\":\"Giada Longo\",\"url\":\"https:\\\/\\\/sandsiv.com\\\/it\\\/author\\\/giada\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SANDSIV e Applied Consulting - sandsiv+","description":"SANDSIV e Applied Consulting firmano una partnership per promuovere la Centralit\u00e0 del Cliente e l'Innovazione Aziendale in Italia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sandsiv.com\/it\/sandsiv-e-applied-consulting\/","og_locale":"it_IT","og_type":"article","og_title":"SANDSIV e Applied Consulting","og_description":"SANDSIV e Applied Consulting firmano una partnership per promuovere la Centralit\u00e0 del Cliente e l'Innovazione Aziendale in Italia.","og_url":"https:\/\/sandsiv.com\/it\/sandsiv-e-applied-consulting\/","og_site_name":"sandsiv+","article_published_time":"2023-11-23T07:40:25+00:00","og_image":[{"width":3375,"height":3375,"url":"https:\/\/sandsiv.com\/wp-content\/uploads\/2023\/11\/Sandsiv-social-IG-2023-11-21T162033.904.png","type":"image\/png"}],"author":"Giada Longo","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Giada Longo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sandsiv.com\/it\/sandsiv-e-applied-consulting\/#article","isPartOf":{"@id":"https:\/\/sandsiv.com\/it\/sandsiv-e-applied-consulting\/"},"author":{"name":"Giada Longo","@id":"https:\/\/sandsiv.com\/#\/schema\/person\/a5540ae6ab27ce7f4459b6192a72b8da"},"headline":"SANDSIV e Applied Consulting","datePublished":"2023-11-23T07:40:25+00:00","mainEntityOfPage":{"@id":"https:\/\/sandsiv.com\/it\/sandsiv-e-applied-consulting\/"},"wordCount":4,"publisher":{"@id":"https:\/\/sandsiv.com\/#organization"},"image":{"@id":"https:\/\/sandsiv.com\/it\/sandsiv-e-applied-consulting\/#primaryimage"},"thumbnailUrl":"https:\/\/sandsiv.com\/wp-content\/uploads\/2023\/11\/Sandsiv-social-IG-2023-11-21T162033.904.png","keywords":["breaking news","cxm","partner","partner program","sandsiv","voc"],"articleSection":["Non categorizzato"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/sandsiv.com\/it\/sandsiv-e-applied-consulting\/","url":"https:\/\/sandsiv.com\/it\/sandsiv-e-applied-consulting\/","name":"SANDSIV e Applied Consulting - sandsiv+","isPartOf":{"@id":"https:\/\/sandsiv.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sandsiv.com\/it\/sandsiv-e-applied-consulting\/#primaryimage"},"image":{"@id":"https:\/\/sandsiv.com\/it\/sandsiv-e-applied-consulting\/#primaryimage"},"thumbnailUrl":"https:\/\/sandsiv.com\/wp-content\/uploads\/2023\/11\/Sandsiv-social-IG-2023-11-21T162033.904.png","datePublished":"2023-11-23T07:40:25+00:00","description":"SANDSIV e Applied Consulting firmano una partnership per promuovere la Centralit\u00e0 del Cliente e l'Innovazione Aziendale in Italia.","breadcrumb":{"@id":"https:\/\/sandsiv.com\/it\/sandsiv-e-applied-consulting\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sandsiv.com\/it\/sandsiv-e-applied-consulting\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sandsiv.com\/it\/sandsiv-e-applied-consulting\/#primaryimage","url":"https:\/\/sandsiv.com\/wp-content\/uploads\/2023\/11\/Sandsiv-social-IG-2023-11-21T162033.904.png","contentUrl":"https:\/\/sandsiv.com\/wp-content\/uploads\/2023\/11\/Sandsiv-social-IG-2023-11-21T162033.904.png","width":3375,"height":3375},{"@type":"BreadcrumbList","@id":"https:\/\/sandsiv.com\/it\/sandsiv-e-applied-consulting\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sandsiv.com\/it\/"},{"@type":"ListItem","position":2,"name":"SANDSIV e Applied Consulting"}]},{"@type":"WebSite","@id":"https:\/\/sandsiv.com\/#website","url":"https:\/\/sandsiv.com\/","name":"sandsiv+","description":"Customer Intelligence Made In Switzerland","publisher":{"@id":"https:\/\/sandsiv.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sandsiv.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/sandsiv.com\/#organization","name":"sandsiv+","url":"https:\/\/sandsiv.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/sandsiv.com\/#\/schema\/logo\/image\/","url":"https:\/\/sandsiv.com\/wp-content\/uploads\/2021\/08\/logo-light-normal.svg","contentUrl":"https:\/\/sandsiv.com\/wp-content\/uploads\/2021\/08\/logo-light-normal.svg","width":376,"height":67,"caption":"sandsiv+"},"image":{"@id":"https:\/\/sandsiv.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/sandsiv.com\/#\/schema\/person\/a5540ae6ab27ce7f4459b6192a72b8da","name":"Giada Longo","url":"https:\/\/sandsiv.com\/it\/author\/giada\/"}]}},"_links":{"self":[{"href":"https:\/\/sandsiv.com\/it\/wp-json\/wp\/v2\/posts\/11449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sandsiv.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sandsiv.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sandsiv.com\/it\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sandsiv.com\/it\/wp-json\/wp\/v2\/comments?post=11449"}],"version-history":[{"count":0,"href":"https:\/\/sandsiv.com\/it\/wp-json\/wp\/v2\/posts\/11449\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sandsiv.com\/it\/wp-json\/wp\/v2\/media\/11458"}],"wp:attachment":[{"href":"https:\/\/sandsiv.com\/it\/wp-json\/wp\/v2\/media?parent=11449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sandsiv.com\/it\/wp-json\/wp\/v2\/categories?post=11449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sandsiv.com\/it\/wp-json\/wp\/v2\/tags?post=11449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}