
{"id":11913,"date":"2023-12-19T13:16:32","date_gmt":"2023-12-19T13:16:32","guid":{"rendered":"https:\/\/sandsiv.com\/?page_id=11913"},"modified":"2024-08-06T13:14:22","modified_gmt":"2024-08-06T13:14:22","slug":"empieza-un-programa-voe","status":"publish","type":"page","link":"https:\/\/sandsiv.com\/es\/casos-practicos\/empieza-un-programa-voe\/","title":{"rendered":"Caso pr\u00e1ctico &#8211; Empieza un programa VoE"},"content":{"rendered":"<div id=\"banner-block_d0c896fe2e1a824c61901d8f8f00abef\"\r\n    class=\"banner scroll-fade\">\r\n    <div\r\n        class=\"module mt_0  mb_0\">\r\n        <div class=\"container\">\r\n            <div class=\"banner__inner\">\r\n                <div class=\"banner__data\">\r\n                                        <h1 class=\"heading\"><span style=\"color: #BF2025;\">Caso pr\u00e1ctico<\/span><strong\r\n                            class=\"heading_red\"><span style=\"color:  #4F4F4F;\">Empieza un programa VoE<\/span><\/strong>                    <\/h1>\r\n                                                            <div class=\"description\"><div style=\"margin-bottom: 20px;\">\r\n  <div style=\"margin-right: 20px;\">\r\n    <p style=\"font-size: 0.8em; color: #4F4F4F; margin-bottom: 5px;\"><em><span style=\"color:  #4F4F4F;\">Tiempo estimado de lectura: 3 minutos<\/span><\/em><\/p>\r\n  <\/div>\r\n\r\n  <div style=\"font-size: 0.8em; color:  #000000; display: flex;\">\r\n    <a style=\"color: #000; padding: 3px 8px; border: 1px solid #000; border-radius: 5px; text-decoration: none; transition: all 0.3s ease-in-out; margin-right: 5px;\"  onmouseover=\"this.style.backgroundColor='#000'; this.style.color='#fff';\" onmouseout=\"this.style.backgroundColor='transparent'; this.style.color='#000';\">Empleados<\/a>\r\n    <a style=\"color: #000; padding: 3px 8px; border: 1px solid #000; border-radius: 5px; text-decoration: none; transition: all 0.3s ease-in-out; margin-right: 5px;\" onmouseover=\"this.style.backgroundColor='#000'; this.style.color='#fff';\" onmouseout=\"this.style.backgroundColor='transparent'; this.style.color='#000';\">Empoderamiento<\/a>\r\n  <\/div>\r\n<\/div>                    <\/div>                                                                                                <\/div>\r\n                <div class=\"banner__media\">\r\n                                        <div class=\"banner__image\">\r\n                        <picture class=\"image\">\r\n                            <source srcset=\"https:\/\/sandsiv.com\/wp-content\/uploads\/2023\/12\/sandsiv_use-case_VOE.png\">\r\n                            <img decoding=\"async\" src=\"https:\/\/sandsiv.com\/wp-content\/uploads\/2023\/12\/sandsiv_use-case_VOE.png\"\r\n                                alt=\"Voice of employee sa\" \/>\r\n                        <\/picture>\r\n                    <\/div>\r\n                                                                            <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\n\n\n<div id=\"post_content_with_download_link_two_columns-block_e5a25495765e20e686de956b7a7615c3\" class=\"post_content_with_download_link_two_columns scroll-fade\">\n    <div class=\"module mt_0 \">                \n        <div class=\"container\">\n            <div class=\"post_content_with_download_link_two_columns_inner\"> \n                \t\t\t\t\t<div class=\"content_section\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content_section_inner\">\n                                                                    <div class=\"heading_text\">\n                                        <p><!--         <span style=\"display: none;\">Empieza un programa VoE<\/span>     --><\/p>                                    <\/div>\n                                                                                                    <div class=\"content\">\n                                        <p>Dicen que escuchar a los empleados es tan importante como escuchar a los clientes.<\/p>\n<p>Si amplificas las voces de tus empleados, no s\u00f3lo mejorar\u00e1s las experiencias de los clientes, sino que tambi\u00e9n fomentar\u00e1s una cultura de compromiso e innovaci\u00f3n dentro de tu empresa. Esta idea constituye la piedra angular del enfoque de SANDSIV para comprender y mejorar las experiencias.<\/p>\n<p>Programa una reuni\u00f3n de 30 minutos con nuestro asesor de CX para explorar c\u00f3mo este principio cobra vida.<\/p>\n<p>&nbsp;<\/p>\n<p><a style=\"color: white; font-size: 14px; font-weight: 500; padding: 15px 20px; border: 1px solid #bf2025; border-radius: 40px; text-decoration: none; transition: all 0.3s ease-in-out; margin-right: 5px; background-color: #bf2025;\" href=\"https:\/\/sandsiv.com\/contact-with-cx-advisor\/\">Habla con un experto<\/a><\/p>\n                                    <\/div>\n                                \t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                                <div class=\"download_link_section\">\n                    <div class=\"download_link_section_inner\">\n                                                                                                                                                                                                                <div class=\"contact_form_section\">\n                                    <br><br> <div style=\"margin-top: 0; padding: 20px; color: #FFFFFF; background-color: #4F4F4F; border-radius: 8px; margin-left: 50px;\">     <h6 style=\"font-size: 14px; font-weight: bold; margin-bottom: 15px; margin-top: 0; position: relative;\">         Obteniendo el ROI:         <span id=\"underline\" style=\"position: absolute; bottom: -3px; left: 0; width: 0; height: 2px; background-color: #4ECDC4; transition: width 0.3s ease;\"><\/span>     <\/h6>      <script>         const title = document.querySelector('h6');         const underline = document.getElementById('underline');          title.addEventListener('mouseenter', function () {             underline.style.width = '100%';         });          title.addEventListener('mouseleave', function () {             underline.style.width = '0';         });     <\/script>      <p style=\"margin-bottom: 15px; font-size: 14px;\">En un panorama en el que casi el 70% de los directivos contempla la posibilidad de cambiar a puestos que den prioridad al bienestar (Deloitte), considere esta historia de \u00e9xito. Una empresa italiana de m\u00e1s de 5.000 empleados empez\u00f3 a recopilar tanto VoC como VoE utilizando sandsiv+, obteniendo resultados excepcionales en la fase inicial del proyecto:<\/p>     <ul style=\"list-style-type: square; padding-left: 20px; margin-bottom: 15px; font-size: 14px;\">         <li>El 95% de los directivos y altos cargos reconocieron la importancia de implantar un programa de VoE para el bienestar laboral de su empresa. <\/li>         <li>El porcentaje de empleados que creen que sus directivos se preocupan por su bienestar se dispar\u00f3 del 43% al 76% en s\u00f3lo 6 meses. <\/li><li>Tras un a\u00f1o de implicaci\u00f3n activa de sus empleados, la empresa logr\u00f3 un aumento del 11% en productividad y un notable incremento del 32% en rentabilidad en comparaci\u00f3n con su competencia.<\/li>     <\/ul>     <p style=\"margin-bottom: 0; font-size: 14px;\">Esta historia de \u00e9xito puede ser la <b>tuya.<\/b><\/p> <\/div>                                <\/div>\n                                                                                <\/div>\n\n\t\t\t\t\t<\/div>\n\n\n  \n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n\r\n<div id=\"blog_post_content-block_abfa0f7f658ec2869fe23ff515027edd\" class=\"blog_post_content scroll-fade\">\r\n    <div class=\"module mt_0  mb_0\">\r\n\r\n                    <div class=\"container\">\r\n                                \r\n            <div class=\"blog_post_content_inner\"> \r\n                                    <div class=\"heading_section\">\r\n                        <div class=\"heading_text h1\">\r\n                            <span style=\"display: none;\">Caso pr\u00e1ctico &#8211; Empieza un programa VoE<\/span>                             <\/div>\r\n                    <\/div>\r\n                                                    <div class=\"content_section\">\r\n                        <h2>Buenas pr\u00e1cticas<\/h2>\n<p>Con <span style=\"color: #bf2025;\"><a style=\"color: #bf2025;\" href=\"https:\/\/sandsiv.com\/es\/\">sandsiv+<\/a><\/span>, no tienes que pedir la opini\u00f3n de tus empleados, pero puedes escucharla. Nos adherimos al mismo marco integral utilizado para captar las opiniones de los clientes: <span style=\"color: #bf2025;\"><strong>escuchar, analizar, integrar, mejorar, medir<\/strong><\/span>.<\/p>\n<p><strong>Establece una cultura de la opini\u00f3n:<\/strong> Crea v\u00edas de comunicaci\u00f3n abiertas y transparentes, como encuestas, pero tambi\u00e9n grupos de discusi\u00f3n y conversaciones individuales, para animar a los empleados a expresar sus opiniones y preocupaciones.<\/p>\n<p><strong>Escuchar y responder:<\/strong> Recopila y analiza peri\u00f3dicamente las opiniones de los empleados y adopte medidas concretas para abordar los problemas detectados y aplicar cambios positivos.<\/p>\n<p><strong>Analizar y comprender:<\/strong> Utiliza herramientas anal\u00edticas avanzadas para profundizar en las opiniones de los empleados, obteniendo informaci\u00f3n valiosa sobre tendencias, patrones y problemas subyacentes que impulsan el sentimiento de los empleados.<\/p>\n<p><strong>Integrar las opiniones:<\/strong> Incorpora las opiniones de los empleados en los procesos de toma de decisiones, las pol\u00edticas organizativas y las iniciativas estrat\u00e9gicas para garantizar que las voces de los empleados se escuchen y se valoren en toda la organizaci\u00f3n.<\/p>\n<p><strong>Mejorar los procesos:<\/strong> Utiliza la opini\u00f3n de los empleados como catalizador para la mejora de los procesos, la innovaci\u00f3n y el desarrollo organizativo, impulsando la mejora continua de la experiencia de los empleados.<\/p>\n<p><strong>Medir el impacto:<\/strong> Evalua peri\u00f3dicamente la eficacia de los cambios e iniciativas implementados a trav\u00e9s de m\u00e9tricas e indicadores clave de rendimiento, garantizando que los esfuerzos para mejorar la experiencia de los empleados produzcan resultados tangibles y resultados positivos.<\/p>\n<p>&nbsp;<\/p>\n<p><a style=\"color: white; font-size: 14px; font-weight: 500; padding: 15px 20px; border: 1px solid #bf2025; border-radius: 40px; text-decoration: none; transition: all 0.3s ease-in-out; margin-right: 5px; background-color: #bf2025;\" href=\"https:\/\/sandsiv.com\/es\/quiero-ver-una-demo\">Quiero ver una demo<\/a><\/p>\n<p>&nbsp;<\/p>\n                    <\/div>\r\n                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\n\n\r\n<div id=\"blog_post_content-block_6595b9c64e9bf5378f86d8b82137cf0a\" class=\"blog_post_content scroll-fade\">\r\n    <div class=\"module  mb_0\">\r\n\r\n                    <div class=\"container\">\r\n                                \r\n            <div class=\"blog_post_content_inner\"> \r\n                                    <div class=\"heading_section\">\r\n                        <div class=\"heading_text h1\">\r\n                            <p><!--         <span style=\"display: none;\">Caso pr\u00e1ctico - Empieza un programa VoE<\/span>     --><\/p>                        <\/div>\r\n                    <\/div>\r\n                                                    <div class=\"content_section\">\r\n                        <h2><\/h2>\n<h2>Excelencia VoE<\/h2>\n<p><a href=\"https:\/\/sandsiv.com\/es\/\"><span style=\"color: #bf2025;\">sandsiv+<\/span><\/a> ofrece un potente software de VoE crucial para fomentar culturas inclusivas en el lugar de trabajo. Personalizable y din\u00e1mico, proporciona a las organizaciones informaci\u00f3n valiosa para el crecimiento de los empleados.<\/p>\n<p><strong>Mecanismos de feedback personalizados:<\/strong><br \/>\nsandsiv+ permite personalizar los m\u00e9todos de recogida de feedback como <a href=\"https:\/\/sandsiv.com\/es\/encuestas\/\"><span style=\"color: #bf2025;\">encuestas<\/span><\/a>, sondeos u otros mecanismos de feedback. Estos pueden ser adaptados para recopilar informaci\u00f3n sobre diversos aspectos como la satisfacci\u00f3n de los empleados, el compromiso, la cultura de trabajo, y mucho m\u00e1s.<\/p>\n<p><strong>Informes y an\u00e1lisis personalizados:<\/strong><br \/>\nsandsiv+ ofrece funciones personalizables de informes y an\u00e1lisis. Esto permite a las empresas generar informes y visualizar datos espec\u00edficos para sus necesidades, permitiendo una mejor toma de decisiones basada en conocimientos personalizados.<\/p>\n<p><strong>Cuadros de mando flexibles:<\/strong><br \/>\nEl software proporciona <span style=\"color: #bf2025;\"><a style=\"color: #bf2025;\" href=\"https:\/\/sandsiv.com\/es\/cuadros-de-mando-avanzados\/\">cuadros de mando personalizables<\/a><\/span> que se pueden personalizar para mostrar las m\u00e9tricas y KPI m\u00e1s relevantes en funci\u00f3n de las prioridades y objetivos de la empresa.<\/p>\n<p><strong>Adaptabilidad a la cultura de la empresa:<\/strong><br \/>\nsandsiv+ puede adaptarse para reflejar la cultura y los valores \u00fanicos de la empresa. Puede incorporar terminolog\u00edas espec\u00edficas, matices culturales y referencias internas para resonar mejor con los empleados.<\/p>\n<p><strong>Integraci\u00f3n con los sistemas existentes:<\/strong><br \/>\nsandsiv+ <a href=\"https:\/\/sandsiv.com\/es\/integraciones\/\"><span style=\"color: #bf2025;\">puede integrarse<\/span><\/a> con los sistemas de RRHH existentes, plataformas de comunicaci\u00f3n u otro software relevante dentro de la organizaci\u00f3n. Esto garantiza un flujo de datos sin fisuras y evita la duplicaci\u00f3n de esfuerzos.<\/p>\n<p><strong>Planes de acci\u00f3n espec\u00edficos:<\/strong><br \/>\nsandsiv+ permite la creaci\u00f3n de <span style=\"color: #bf2025;\"><a style=\"color: #bf2025;\" href=\"https:\/\/sandsiv.com\/es\/close-the-loop-interno\/\">planes de acci\u00f3n<\/a><\/span> espec\u00edficos basados en el feedback recibido. Estos planes pueden personalizarse para abordar \u00e1reas espec\u00edficas de mejora identificadas a trav\u00e9s del feedback de los empleados.<\/p>\n<p><strong>Estrategias de compromiso de los empleados:<\/strong><br \/>\nApoya la personalizaci\u00f3n de las estrategias de compromiso permitiendo a las empresas personalizar las iniciativas que resuenan con su fuerza de trabajo, fomentando un equipo m\u00e1s comprometido y motivado.<\/p>\n<p><strong>Escalabilidad y expansi\u00f3n:<\/strong><br \/>\nsandsiv+ puede escalarse y ampliarse a medida que crece la empresa. Se adapta a los cambios de tama\u00f1o, estructura o distribuci\u00f3n geogr\u00e1fica de la organizaci\u00f3n, garantizando que la estrategia de VOE siga siendo eficaz.<\/p>\n<p><strong>Seguridad y normas de cumplimiento:<\/strong><br \/>\nLa personalizaci\u00f3n puede incluir medidas de seguridad espec\u00edficas y normas de cumplimiento exigidas por la empresa, garantizando que los datos de los empleados est\u00e9n seguros y alineados con los requisitos normativos.<\/p>\n<p>M\u00e1s all\u00e1 de la Voz del Empleado (VOE), la plataforma sandsiv+ <strong>integra a la perfecci\u00f3n la VoE y <a href=\"https:\/\/sandsiv.com\/es\/escucha-la-voz-del-cliente\/\"><span style=\"color: #bf2025;\">la Voz del Cliente (VoC)<\/span><\/a> en una \u00fanica y potente soluci\u00f3n.<\/strong> Aproveche la informaci\u00f3n de empleados y clientes para potenciar la mejora integral del negocio, fomentando un enfoque hol\u00edstico del \u00e9xito. Es m\u00e1s que integraci\u00f3n; es transformaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p><a style=\"color: white; font-size: 14px; font-weight: 500; padding: 15px 20px; border: 1px solid #bf2025; border-radius: 40px; text-decoration: none; transition: all 0.3s ease-in-out; margin-right: 5px; background-color: #bf2025;\" href=\"https:\/\/sandsiv.com\/es\/quiero-ver-una-demo\">Quiero ver una demo<\/a><\/p>\n<p>&nbsp;<\/p>\n                    <\/div>\r\n                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\n\n\r\n<div id=\"frames_section-block_0baa4cb379fd6f51ceb3de7f50d4c111\" class=\"frames_section scroll-fade\">\r\n    <div class=\"module mt_0  mb_0\">  \r\n        <div class=\"bg_clr_section bg_clr_red\">               \r\n            <div class=\"container\">\r\n                <div class=\"frames_section_inner\"> \r\n                                            <div class=\"heading\">\r\n                            \u00bfQuieres saber m\u00e1s?                        <\/div>\r\n                                                                <div class=\"text\">\r\n                            <p>Nuestros expertos en CX est\u00e1n aqu\u00ed para ayudarte a encontrar la soluci\u00f3n perfecta.<\/p>\n                        <\/div>\r\n                                                                <div class=\"button_section\">\r\n                            <a class=\"btn btn--white \" href=\"https:\/\/sandsiv.com\/es\/contacto-con-cx-advisor\/\" >\r\n                                Habla con un experto                            <\/a>\r\n                        <\/div>\r\n                                    <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":11919,"parent":11763,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","footnotes":""},"class_list":["post-11913","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Caso pr\u00e1ctico - Empieza un programa VoE - sandsiv+<\/title>\n<meta name=\"description\" content=\"Si amplificas las voces de tus empleados fomentar\u00e1s una cultura de compromiso e innovaci\u00f3n dentro de tu empresa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sandsiv.com\/es\/casos-practicos\/empieza-un-programa-voe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caso pr\u00e1ctico - Empieza un programa VoE\" \/>\n<meta property=\"og:description\" content=\"Si amplificas las voces de tus empleados fomentar\u00e1s una cultura de compromiso e innovaci\u00f3n dentro de tu empresa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sandsiv.com\/es\/casos-practicos\/empieza-un-programa-voe\/\" \/>\n<meta property=\"og:site_name\" content=\"sandsiv+\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-06T13:14:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sandsiv.com\/wp-content\/uploads\/2023\/12\/sandsiv_use-case_VOE.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1233\" \/>\n\t<meta property=\"og:image:height\" content=\"1286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sandsiv.com\\\/es\\\/casos-practicos\\\/empieza-un-programa-voe\\\/\",\"url\":\"https:\\\/\\\/sandsiv.com\\\/es\\\/casos-practicos\\\/empieza-un-programa-voe\\\/\",\"name\":\"Caso pr\u00e1ctico - Empieza un programa VoE - sandsiv+\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sandsiv.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sandsiv.com\\\/es\\\/casos-practicos\\\/empieza-un-programa-voe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sandsiv.com\\\/es\\\/casos-practicos\\\/empieza-un-programa-voe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sandsiv.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/sandsiv_use-case_VOE.png\",\"datePublished\":\"2023-12-19T13:16:32+00:00\",\"dateModified\":\"2024-08-06T13:14:22+00:00\",\"description\":\"Si amplificas las voces de tus empleados fomentar\u00e1s una cultura de compromiso e innovaci\u00f3n dentro de tu empresa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sandsiv.com\\\/es\\\/casos-practicos\\\/empieza-un-programa-voe\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sandsiv.com\\\/es\\\/casos-practicos\\\/empieza-un-programa-voe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sandsiv.com\\\/es\\\/casos-practicos\\\/empieza-un-programa-voe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sandsiv.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/sandsiv_use-case_VOE.png\",\"contentUrl\":\"https:\\\/\\\/sandsiv.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/sandsiv_use-case_VOE.png\",\"width\":1233,\"height\":1286,\"caption\":\"voice of employee sandsiv\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sandsiv.com\\\/es\\\/casos-practicos\\\/empieza-un-programa-voe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sandsiv.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casos pr\u00e1cticos\",\"item\":\"https:\\\/\\\/sandsiv.com\\\/es\\\/casos-practicos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Caso pr\u00e1ctico &#8211; Empieza un programa VoE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sandsiv.com\\\/#website\",\"url\":\"https:\\\/\\\/sandsiv.com\\\/\",\"name\":\"sandsiv+\",\"description\":\"Customer Intelligence Made In Switzerland\",\"publisher\":{\"@id\":\"https:\\\/\\\/sandsiv.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sandsiv.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sandsiv.com\\\/#organization\",\"name\":\"sandsiv+\",\"url\":\"https:\\\/\\\/sandsiv.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sandsiv.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sandsiv.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logo-light-normal.svg\",\"contentUrl\":\"https:\\\/\\\/sandsiv.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logo-light-normal.svg\",\"width\":376,\"height\":67,\"caption\":\"sandsiv+\"},\"image\":{\"@id\":\"https:\\\/\\\/sandsiv.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Caso pr\u00e1ctico - Empieza un programa VoE - sandsiv+","description":"Si amplificas las voces de tus empleados fomentar\u00e1s una cultura de compromiso e innovaci\u00f3n dentro de tu empresa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sandsiv.com\/es\/casos-practicos\/empieza-un-programa-voe\/","og_locale":"es_ES","og_type":"article","og_title":"Caso pr\u00e1ctico - Empieza un programa VoE","og_description":"Si amplificas las voces de tus empleados fomentar\u00e1s una cultura de compromiso e innovaci\u00f3n dentro de tu empresa.","og_url":"https:\/\/sandsiv.com\/es\/casos-practicos\/empieza-un-programa-voe\/","og_site_name":"sandsiv+","article_modified_time":"2024-08-06T13:14:22+00:00","og_image":[{"width":1233,"height":1286,"url":"https:\/\/sandsiv.com\/wp-content\/uploads\/2023\/12\/sandsiv_use-case_VOE.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sandsiv.com\/es\/casos-practicos\/empieza-un-programa-voe\/","url":"https:\/\/sandsiv.com\/es\/casos-practicos\/empieza-un-programa-voe\/","name":"Caso pr\u00e1ctico - Empieza un programa VoE - sandsiv+","isPartOf":{"@id":"https:\/\/sandsiv.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sandsiv.com\/es\/casos-practicos\/empieza-un-programa-voe\/#primaryimage"},"image":{"@id":"https:\/\/sandsiv.com\/es\/casos-practicos\/empieza-un-programa-voe\/#primaryimage"},"thumbnailUrl":"https:\/\/sandsiv.com\/wp-content\/uploads\/2023\/12\/sandsiv_use-case_VOE.png","datePublished":"2023-12-19T13:16:32+00:00","dateModified":"2024-08-06T13:14:22+00:00","description":"Si amplificas las voces de tus empleados fomentar\u00e1s una cultura de compromiso e innovaci\u00f3n dentro de tu empresa.","breadcrumb":{"@id":"https:\/\/sandsiv.com\/es\/casos-practicos\/empieza-un-programa-voe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sandsiv.com\/es\/casos-practicos\/empieza-un-programa-voe\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sandsiv.com\/es\/casos-practicos\/empieza-un-programa-voe\/#primaryimage","url":"https:\/\/sandsiv.com\/wp-content\/uploads\/2023\/12\/sandsiv_use-case_VOE.png","contentUrl":"https:\/\/sandsiv.com\/wp-content\/uploads\/2023\/12\/sandsiv_use-case_VOE.png","width":1233,"height":1286,"caption":"voice of employee sandsiv"},{"@type":"BreadcrumbList","@id":"https:\/\/sandsiv.com\/es\/casos-practicos\/empieza-un-programa-voe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sandsiv.com\/es\/"},{"@type":"ListItem","position":2,"name":"Casos pr\u00e1cticos","item":"https:\/\/sandsiv.com\/es\/casos-practicos\/"},{"@type":"ListItem","position":3,"name":"Caso pr\u00e1ctico &#8211; Empieza un programa VoE"}]},{"@type":"WebSite","@id":"https:\/\/sandsiv.com\/#website","url":"https:\/\/sandsiv.com\/","name":"sandsiv+","description":"Customer Intelligence Made In Switzerland","publisher":{"@id":"https:\/\/sandsiv.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sandsiv.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sandsiv.com\/#organization","name":"sandsiv+","url":"https:\/\/sandsiv.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sandsiv.com\/#\/schema\/logo\/image\/","url":"https:\/\/sandsiv.com\/wp-content\/uploads\/2021\/08\/logo-light-normal.svg","contentUrl":"https:\/\/sandsiv.com\/wp-content\/uploads\/2021\/08\/logo-light-normal.svg","width":376,"height":67,"caption":"sandsiv+"},"image":{"@id":"https:\/\/sandsiv.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sandsiv.com\/es\/wp-json\/wp\/v2\/pages\/11913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sandsiv.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sandsiv.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sandsiv.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/sandsiv.com\/es\/wp-json\/wp\/v2\/comments?post=11913"}],"version-history":[{"count":0,"href":"https:\/\/sandsiv.com\/es\/wp-json\/wp\/v2\/pages\/11913\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/sandsiv.com\/es\/wp-json\/wp\/v2\/pages\/11763"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sandsiv.com\/es\/wp-json\/wp\/v2\/media\/11919"}],"wp:attachment":[{"href":"https:\/\/sandsiv.com\/es\/wp-json\/wp\/v2\/media?parent=11913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}